{"id":18158,"date":"2022-04-01T10:42:00","date_gmt":"2022-04-01T08:42:00","guid":{"rendered":"https:\/\/perihelio.es\/condiciones-de-contratacion\/"},"modified":"2023-09-29T18:38:12","modified_gmt":"2023-09-29T16:38:12","slug":"condiciones-de-contratacion","status":"publish","type":"page","link":"https:\/\/perihelio.es\/en\/condiciones-de-contratacion\/","title":{"rendered":"Condiciones de contrataci\u00f3n"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"18158\" class=\"elementor elementor-18158 elementor-18058\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4eb984 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4eb984\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50d36f0\" data-id=\"50d36f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73ee94d elementor-widget elementor-widget-heading\" data-id=\"73ee94d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">CONDICIONES CONTRACTUALES DE COMPRA<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6a08fc elementor-widget elementor-widget-text-editor\" data-id=\"e6a08fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">El principal fin de mi Sitio web es la exposici\u00f3n y difusi\u00f3n de mis obras art\u00edsticas. Las reproducciones (impresiones digitales seriadas, serigraf\u00edas u otros tipos)<\/span> <span style=\"font-weight: 400\">de algunas de mis obras podr\u00e1n ser adquiridas conforme a las condiciones de este documento.<\/span><span style=\"font-weight: 400\">\u00a0<\/span><\/p><p><span style=\"font-weight: 400\">Las obras originales se pueden adquirir previo encargo espec\u00edfico a trav\u00e9s del correo electr\u00f3nico:<\/span> <a href=\"mailto:peri.h3lio@gmail.com\"><span style=\"font-weight: 400\">peri.h3lio@gmail.com<\/span><\/a><span style=\"font-weight: 400\">\u00a0\u00a0<\/span><\/p><p><span style=\"font-weight: 400\">A continuaci\u00f3n se expone el documento contractual que regir\u00e1 la compra de mis obras art\u00edsticas a trav\u00e9s del sitio web <\/span><a href=\"https:\/\/perihelio.es\/\"><span style=\"font-weight: 400\">https:\/\/perihelio.es\/<\/span><\/a><span style=\"font-weight: 400\"> propiedad de Pedro Amutio Fern\u00e1ndez; o bien a trav\u00e9s del correo electr\u00f3nico:<\/span> <a href=\"mailto:peri.h3lio@gmail.com\"><span style=\"font-weight: 400\">peri.h3lio@gmail.com<\/span><\/a><\/p><p><span style=\"font-weight: 400\">Por ello te solicito que leas detenidamente las presentes condiciones antes de realizar tu pedido. Las presentes condiciones tendr\u00e1n un periodo de validez indefinido, aunque me reservo el derecho a modificarlas. En cualquier caso, los posibles cambios no afectar\u00e1n a los pedidos realizados con anterioridad a la modificaci\u00f3n.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ea5cab elementor-widget elementor-widget-text-editor\" data-id=\"9ea5cab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Informaci\u00f3n general<\/h3><p><span style=\"font-weight: 400\">El procedimiento de compra ser\u00e1 realizado en el idioma castellano. En caso de que<\/span> <span style=\"font-weight: 400\">quieras realizarlo en ingl\u00e9s deber\u00e1s seleccionarlo antes de iniciar el procedimiento de contrataci\u00f3n, en la pesta\u00f1a de selecci\u00f3n de idioma del men\u00fa vertical situado a la izquierda de la pantalla.<\/span><\/p><p><span style=\"font-weight: 400\">Para cualquier informaci\u00f3n sobre el pedido, podr\u00e1s contactarme preferentemente v\u00eda correo electr\u00f3nico en la direcci\u00f3n de e-mail\u00a0<\/span><a href=\"mailto:peri.h3lio@gmail.com\"><span style=\"font-weight: 400\">peri.h3lio@gmail.com<\/span><\/a><span style=\"font-weight: 400\">, o bien en el tel\u00e9fono +34 669 54 06 21.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f954110 elementor-widget elementor-widget-text-editor\" data-id=\"f954110\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>01. C\u00d3MO HACER TU PEDIDO:<\/h3><p><span style=\"font-weight: 400;\">El procedimiento de compra se lleva a cabo de forma completamente electr\u00f3nica a trav\u00e9s del sitio web. En el caso de querer adquirir una obra original se deber\u00e1 realizar el pedido previamente a trav\u00e9s del correo electr\u00f3nico:<\/span> <span style=\"font-weight: 400;\">peri.h3lio@gmail.com<\/span><\/p><p><b>1.1. Selecci\u00f3n del pedido:<\/b><\/p><p><span style=\"font-weight: 400;\">Para iniciar el proceso \u00fanicamente debes seleccionar la obra u obras que desees adquirir y pulsar el bot\u00f3n de &#8220;a\u00f1adir al carrito\u201d.<\/span><\/p><p><span style=\"font-weight: 400;\">En aquellas obras que s\u00ed se puedan incorporar al &#8220;carrito&#8221; se informar\u00e1 del nombre de la misma, del tipo de t\u00e9cnica de reproducci\u00f3n del que se trata (impresi\u00f3n digital, serigraf\u00eda, etc.) y si son seriadas o no. En caso de que sean originales, se har\u00e1 expresa menci\u00f3n. Tambi\u00e9n se informar\u00e1 del precio de cada selecci\u00f3n.<\/span><\/p><p><span style=\"font-weight: 400;\">Tras a\u00f1adir una obra concreta, puedes continuar con tu compra, de forma que todas las obras seleccionadas incluidas en el carrito ir\u00e1n sum\u00e1ndose. Cuando hayas\u00a0 terminado la selecci\u00f3n presiona en el bot\u00f3n &#8220;Ver carrito&#8221; para ver el pedido completo, junto con el precio y los gastos de env\u00edo. <\/span><span style=\"font-weight: 400;\">Por defecto se informa de los gastos de env\u00edo<\/span> <span style=\"font-weight: 400;\">desde la zona correspondiente a tu direcci\u00f3n IP<\/span><span style=\"font-weight: 400;\">. Para ver los gastos de env\u00edo a otras zonas se debe presionar en el bot\u00f3n &#8220;cambiar direcci\u00f3n&#8221; y poner la que corresponda, para que se actualicen as\u00ed los gastos de env\u00edo. Si deseas recoger la obra personalmente debes seleccionar la opci\u00f3n &#8220;recogida local en Vigo&#8221;, en cuyo caso no se cobrar\u00e1n gastos de env\u00edo.<\/span><\/p><p><span style=\"font-weight: 400;\">Si has incluido m\u00e1s de una obra art\u00edstica en el &#8220;carrito&#8221; o &#8220;cesta de la compra&#8221;, podr\u00e1s eliminar de la selecci\u00f3n una de ellas o todas, clicando en el bot\u00f3n &#8220;<\/span><span style=\"font-weight: 400;\">x<\/span><span style=\"font-weight: 400;\">&#8220;.<\/span> <span style=\"font-weight: 400;\">En caso de que cambies alguna de las obras del carrito o cesta, variar\u00e1 autom\u00e1ticamente el resumen mostrado en pantalla, junto con el precio correspondiente, que ir\u00e1 cambiando conforme introduzcas o quites alg\u00fan elemento del &#8220;carrito&#8221; de la compra.<\/span><\/p><p><span style=\"font-weight: 400;\">En el momento que ya tengas claro cu\u00e1l va a ser tu pedido, para continuar con la compra presiona el bot\u00f3n <\/span><span style=\"font-weight: 400;\">&#8220;ir al pago&#8221; o &#8220;finalizar y pagar&#8221;.\u00a0\u00a0<\/span><\/p><p><b>1.2. Rellenar el formulario de compra:<\/b><\/p><p><span style=\"font-weight: 400;\">Para continuar con la compra deber\u00e1s cumplimentar un formulario con algunos de tus datos personales, s\u00f3lo los indispensables para llevar a cabo el env\u00edo del pedido y (en su caso) realizar la factura. Los datos m\u00ednimos son tu nombre, apellidos y tel\u00e9fono, la direcci\u00f3n postal en la que desees recibir la factura y el e-mail.<\/span><\/p><p><span style=\"font-weight: 400;\">En caso de que solicites la emisi\u00f3n de la correspondiente factura, se deber\u00e1n facilitar adem\u00e1s los apellidos (o raz\u00f3n social, en caso de que compres en representaci\u00f3n de una empresa), la direcci\u00f3n de facturaci\u00f3n (si es distinta a la de entrega) y el DNI, NIE o NIF, seg\u00fan los casos<\/span><span style=\"font-weight: 400;\">.<\/span><\/p><p><span style=\"font-weight: 400;\">As\u00ed mismo, tambi\u00e9n existe un espacio expresamente habilitado para que puedas realizar observaciones concretas respecto a tu compra.<\/span><\/p><p><span style=\"font-weight: 400;\">Si decides continuar con la compra, <\/span><b>deber\u00e1s leer y aceptar expresamente los presentes t\u00e9rminos y condiciones<\/b><span style=\"font-weight: 400;\">, as\u00ed como la <\/span><b>pol\u00edtica de privacidad<\/b><span style=\"font-weight: 400;\"> del sitio web <\/span><span style=\"font-weight: 400;\">(<\/span><a href=\"\/politica-de-privacidad\"><span style=\"font-weight: 400;\">consultar aqu\u00ed<\/span><\/a><span style=\"font-weight: 400;\">)<\/span><span style=\"font-weight: 400;\">. Una vez realizado lo anterior, pasar\u00e1s a la siguiente fase de compra.<\/span><\/p><p><b>1.3. Proceso de pago:<\/b><\/p><p><span style=\"font-weight: 400;\">Para finalizar el proceso de compra deber\u00e1s seleccionar el medio de pago y efectuarlo, conforme a lo se\u00f1alado en el<\/span> <span style=\"font-weight: 400;\">apartado 3<\/span> <span style=\"font-weight: 400;\">de este mismo documento. Antes de clicar en el bot\u00f3n &#8220;<\/span><span style=\"font-weight: 400;\">Pagar con<\/span><span style=\"font-weight: 400;\"> PayPal&#8221;, o bien en la opci\u00f3n &#8220;Pagar por Coinbase&#8221; (para abonar con criptomonedas), podr\u00e1s ver en pantalla los elementos del pedido y su precio final total; incluidos los impuestos y los gastos de env\u00edo (que en su caso correspondan).<\/span><\/p><p><span style=\"font-weight: 400;\">Una vez finalizado el proceso de pago se mostrar\u00e1 una pantalla con el resumen de la compra realizada. Tambi\u00e9n recibir\u00e1s por email un resumen de dicha compra.<\/span><\/p><p><span style=\"font-weight: 400;\">Este documento es la confirmaci\u00f3n de que la compra se ha realizado con \u00e9xito y te servir\u00e1 de acreditaci\u00f3n para cualquier tipo de reclamaci\u00f3n, siempre y cuando se adjunte el justificante del pago correspondiente. En caso de no recibir dicho correo electr\u00f3nico revisa tu cuenta de &#8220;correo no deseado&#8221; o &#8220;antispam&#8221;, ya que puede haber sido detectado como spam; Si no se encuentra en dicho apartado, te ruego que me lo comuniques lo antes posible para que pueda solucionar el problema.<\/span><\/p><p><span style=\"font-weight: 400;\">A efectos de cumplimiento de los art\u00edculos 27.1.b) y 28.1 de la <\/span><i><span style=\"font-weight: 400;\">Ley 34\/2002, de 11 de julio, de servicios de la sociedad de la informaci\u00f3n y de comercio electr\u00f3nico,<\/span><\/i><span style=\"font-weight: 400;\"> declaro que<\/span> <span style=\"font-weight: 400;\">recibir\u00e9 en mi direcci\u00f3n de correo electr\u00f3nico un resumen de la compra con los datos necesarios para la entrega del pedido<\/span> <span style=\"font-weight: 400;\">(y para enviar la factura, en su caso).<\/span> <span style=\"font-weight: 400;\">Para ver m\u00e1s informaci\u00f3n sobre el plazo de conservaci\u00f3n de estas comunicaciones y de los datos personales consulta pinchando a continuaci\u00f3n en mi <\/span><a href=\"\/politica-de-privacidad\/\"><span style=\"font-weight: 400;\">Pol\u00edtica de Privacidad<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c31f51 elementor-widget elementor-widget-text-editor\" data-id=\"3c31f51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>02. PRECIOS Y GASTOS DE ENV\u00cdO:<\/h3><p><b>2.1. Precios e impuestos:<\/b><\/p><p><span style=\"font-weight: 400;\">Los precios de aquellas de mis obras art\u00edsticas que est\u00e9n a la venta, se expresar\u00e1n en la moneda Euro (\u20ac). Los pagos se podr\u00e1n realizar a trav\u00e9s de la plataforma de PayPal o por medio de la plataforma de pago en criptomoneda, Coinbase Commerce.<\/span><\/p><p><span style=\"font-weight: 400;\">Los precios indicados junto a las obras que est\u00e9n en venta incluyen el IVA y se podr\u00e1n visualizar desde el inicio de la compra.<\/span><\/p><p><span style=\"font-weight: 400;\">En caso de que hayas pedido la emisi\u00f3n de una factura esta se realizar\u00e1 a nombre de la persona o empresa que hayas\u00a0 introducido en el formulario de datos de facturaci\u00f3n en el momento de realizar el pedido.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Esta factura ser\u00e1 enviada junto con la obra adquirida, as\u00ed como <\/span><span style=\"font-weight: 400;\">en PDF a la direcci\u00f3n de correo electr\u00f3nico <\/span><span style=\"font-weight: 400;\">que hayas proporcionado.<\/span><\/p><p><span style=\"font-weight: 400;\">Para cualquier informaci\u00f3n, podr\u00e1s contactar v\u00eda e-mail: <\/span><a href=\"mailto:peri.h3lio@gmail.com\"><span style=\"font-weight: 400;\">peri.h3lio@gmail.com<\/span><\/a> <span style=\"font-weight: 400;\">o a trav\u00e9s del tel\u00e9fono<\/span> <span style=\"font-weight: 400;\">+34 669540621.<\/span><\/p><p><span style=\"font-weight: 400;\">Actualmente no tengo c\u00f3digos ni cupones de descuento. En caso de que los establezca m\u00e1s adelante se informar\u00e1 en el Sitio Web c\u00f3mo obtenerlos.<\/span><\/p><p><b>2.2. Gastos de env\u00edo:<\/b><\/p><p><span style=\"font-weight: 400;\">Los gastos de env\u00edo vendr\u00e1n reflejados antes de finalizar el proceso de compra. Los mismos ser\u00e1n calculados atendiendo al destino del mismo y al coste de dicho pedido (debido al tama\u00f1o y peso), as\u00ed como a los costes de embalaje para proteger la obra. Al final de esta secci\u00f3n, en el<a href=\"https:\/\/perihelio.es\/wp-content\/uploads\/2022\/04\/ANEXO-2-TARIFAS-DE-ENVIO-POR-ZONAS.docx.pdf\" target=\"_blank\" rel=\"noopener\"> Anexo 1<\/a> se reflejan los distintos gastos.<\/span><\/p><p><span style=\"font-weight: 400;\">El empaquetado depender\u00e1 de las caracter\u00edsticas, de las medidas de la obra solicitada y se realizar\u00e1 atendiendo a la mejor forma de proteger la obra de posibles deterioros derivados del env\u00edo. El precio de empaquetado de cualquier obra est\u00e1 incluido en los gastos de env\u00edo<\/span><b>.<\/b><\/p><p><span style=\"font-weight: 400;\">Debido a causas ajenas a esta parte los gastos de env\u00edo podr\u00edan variar, pero si hay contradicci\u00f3n entre la informaci\u00f3n se\u00f1alada en el <a href=\"https:\/\/perihelio.es\/wp-content\/uploads\/2022\/04\/ANEXO-2-TARIFAS-DE-ENVIO-POR-ZONAS.docx.pdf\" target=\"_blank\" rel=\"noopener\">Anexo 1<\/a> con la mostrada en la &#8220;cesta&#8221; o &#8220;carrito de la compra&#8221;,\u00a0 justo antes de finalizar el proceso de compra, ser\u00e1 aplicable la de esta \u00faltima. Por lo que en ning\u00fan caso se cobrar\u00e1 un importe mayor al reflejado en el resumen de la &#8220;cesta&#8221;,<\/span> <span style=\"font-weight: 400;\">ya que esta ser\u00e1 la informaci\u00f3n v\u00e1lida correspondiente a tu pedido concreto.<\/span><\/p><p><a href=\"https:\/\/perihelio.es\/wp-content\/uploads\/2022\/04\/ANEXO-2-TARIFAS-DE-ENVIO-POR-ZONAS.docx.pdf\" target=\"_blank\" rel=\"noopener\">Ver ANEXO 1 &#8211; tarifa de env\u00edos por zonas.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84c6d23 elementor-widget elementor-widget-text-editor\" data-id=\"84c6d23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>03. FORMAS DE PAGO:<\/h3><p><span style=\"font-weight: 400;\">Dado que no deseo recabar datos bancarios tuyos te ofrezco las siguientes formas de pago, para que elijas la que mejor te convenga.<\/span><\/p><p><b>a) Pago a trav\u00e9s de PayPal:<\/b><\/p><p><span style=\"font-weight: 400;\">Puedes realizar el pago en euros mediante la plataforma de PayPal,<\/span> <span style=\"font-weight: 400;\">con toda la seguridad que ofrece esta forma de pago tan com\u00fan.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">&#8211; Condiciones de uso de PayPal:<\/span><\/p><p><a href=\"https:\/\/www.paypal.com\/es\/webapps\/mpp\/ua\/useragreement-full\"><span style=\"font-weight: 400;\">https:\/\/www.paypal.com\/es\/webapps\/mpp\/ua\/useragreement-full<\/span><\/a><\/p><p><strong>b) Pago a trav\u00e9s de tarjeta de cr\u00e9dito:<\/strong><\/p><p>Este m\u00e9todo de pago se realiza tambi\u00e9n a trav\u00e9s de Paypal, con toda la seguridad que ofrece esta plataforma. Las condiciones de uso tambi\u00e9n se pueden consultar en el enlace anterior.<\/p><p><span style=\"font-weight: 400;\">Una vez finalizado el proceso de pago se mostrar\u00e1 una pantalla con el resumen de la compra realizada.<\/span><\/p><p><span style=\"font-weight: 400;\">Las citadas plataformas de pago establecen sus propias condiciones de uso que deber\u00e1s aceptar.<\/span> <span style=\"font-weight: 400;\">Una vez que entres dentro de las plataformas de pago estar\u00e1s fuera del \u00e1mbito de este documento.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b8ca92 elementor-widget elementor-widget-text-editor\" data-id=\"5b8ca92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>04. ENTREGA DE LAS OBRAS PEDIDAS:<\/h3><p><b>4.1. Forma y plazos de entrega:<\/b><\/p><p><b>a) Env\u00edo a trav\u00e9s de empresas de transporte:<\/b><\/p><p><span style=\"font-weight: 400\">La entrega de los pedidos se realizar\u00e1 en la direcci\u00f3n de entrega que t\u00fa mismo indiques en el formulario del pedido. Si prefieres recoger tu paquete en una delegaci\u00f3n u oficina de cualquiera de las empresas transportistas solic\u00edtalo en las observaciones de tu pedido.<\/span> <span style=\"font-weight: 400\">A estos efectos informo de que la empresa con la que realizar\u00e9 los env\u00edos es CORREOS (Sociedad Estatal Correos y Telegrafos, S.A.).<\/span><\/p><p><span style=\"font-weight: 400\">En cualquiera de los casos, no comenzar\u00e9 las gestiones para el env\u00edo de la obra, hasta que no reciba la confirmaci\u00f3n del pago. Una vez recibido el pedido junto con la verificaci\u00f3n del pago, enviar\u00e9 tu pedido dentro de los<\/span> <span style=\"font-weight: 400\">3 d\u00edas laborales siguientes.<\/span><span style=\"font-weight: 400\">\u00a0<\/span><\/p><p><span style=\"font-weight: 400\">El env\u00edo ser\u00e1 ordinario<\/span> <span style=\"font-weight: 400\">y te enviar\u00e9 un mail avisando del env\u00edo.<\/span><\/p><p><span style=\"font-weight: 400\">Por \u00faltimo, no asumir\u00e9 los gastos de realizar un segundo env\u00edo en caso de que la entrega del pedido no llegue a realizarse como consecuencia de que los datos facilitados por ti en el formulario web sean falsos, inexactos o incompletos o cuando la entrega no pueda efectuarse por causas ajenas al vendedor, como lo es la ausencia del destinatario.<\/span><\/p><p><b>b) Recogida del pedido por parte del comprador en la ciudad de Vigo:<\/b><\/p><p><span style=\"font-weight: 400\">Los gastos de env\u00edo no ser\u00e1n cobrados en caso de que hayas seleccionado la opci\u00f3n &#8220;recogida local en Vigo&#8221;, antes de efectuar el pago del pedido (ver apartado 1.1). Una vez tenga preparado el pedido, dentro de los 3 d\u00edas laborales siguientes, me pondr\u00e9 en contacto contigo a trav\u00e9s de la direcci\u00f3n de correo electr\u00f3nico que hayas facilitado, para convenir la fecha y el lugar de la entrega, siempre dentro de la ciudad de Vigo.<\/span><\/p><p><b>4.2. Comprobaciones tras la entrega:<\/b><\/p><p><span style=\"font-weight: 400\">Nada m\u00e1s recibir el pedido debes comprobar que la obra adquirida te ha llegado en perfecto estado, de no ser as\u00ed debes avisarme antes de que pasen 24 horas laborales, al mail\u00a0<\/span><a href=\"mailto:peri.h3lio@gmail.com\"><span style=\"font-weight: 400\">peri.h3lio@gmail.com<\/span><\/a><span style=\"font-weight: 400\">\u00a0o al tel\u00e9fono +34 669540621. S\u00f3lo dispongo de 24 horas para reclamar los da\u00f1os causados durante el transporte, pasado este plazo ser\u00e1 muy complicado que la empresa de transporte acepte nuestra reclamaci\u00f3n, aunque intentar\u00e9 darte la mejor soluci\u00f3n que est\u00e9 en mi mano. Para<\/span> <span style=\"font-weight: 400\">que la reclamaci\u00f3n surta sus efectos debes<\/span> <span style=\"font-weight: 400\">incorporar una fotograf\u00eda en la que se aprecie el deterioro sufrido por el producto y remitir la fotograf\u00eda tanto a la empresa como a mi direcci\u00f3n de correo electr\u00f3nico.<\/span><\/p><p><span style=\"font-weight: 400\">Recomiendo no tirar el embalaje por si decides realizar la devoluci\u00f3n del pedido. Dado que si decides devolver la obra deber\u00e1s devolver tambi\u00e9n el embalaje, conforme se explica en el punto 5.3.<\/span><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9787f7c elementor-widget elementor-widget-text-editor\" data-id=\"9787f7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>05. DERECHO DE DESISTIMIENTO:<\/h3><p><span style=\"font-weight: 400;\">En<\/span> <span style=\"font-weight: 400;\">cumplimiento de la Ley General para la Defensa de los Consumidores y Usuarios, a continuaci\u00f3n te informo de tu derecho de desistimiento y de la forma de ejercitarlo.\u00a0<\/span><\/p><p><b>5.1. Plazo de ejercicio del derecho:<\/b><\/p><p><span style=\"font-weight: 400;\">Entre tus derechos est\u00e1 el de desistir del presente contrato en un plazo de catorce d\u00edas naturales. La ley permite que puedas ejercer tu derecho al desistimiento sin necesidad de dar una justificaci\u00f3n, pero a efectos de mejorar la atenci\u00f3n agradecer\u00eda que me informases del motivo de la decisi\u00f3n, especialmente en el caso de que se deba al estado o caracter\u00edsticas de la obra.<\/span><\/p><p><span style=\"font-weight: 400;\">El plazo de desistimiento se contar\u00e1 a partir del d\u00eda en que recibiste la obra solicitada.<\/span><\/p><p><b>5.2. C\u00f3mo ejercer el derecho:<\/b><\/p><p><span style=\"font-weight: 400;\">Para ejercer el derecho de desistimiento, deber\u00e1s notificarme tu decisi\u00f3n de desistir del contrato mediante una declaraci\u00f3n inequ\u00edvoca (a trav\u00e9s de una carta enviada por correo postal o por correo electr\u00f3nico). Podr\u00e1s utilizar el modelo de formulario de desistimiento que figura al final en el<a href=\"https:\/\/perihelio.es\/wp-content\/uploads\/2022\/04\/ANEXO-1-MODELO-DE-FORMULARIO-DE-DESISTIMIENTO.docx.pdf\" target=\"_blank\" rel=\"noopener\"> Anexo 2<\/a>, aunque su uso no es obligatorio.<\/span><\/p><p><b>5.3. Consecuencias del desistimiento:<\/b><\/p><p><span style=\"font-weight: 400;\">&#8211; En caso de desistimiento te devolver\u00e9 todos los pagos que hayas realizado, incluidos los gastos de entrega, sin ninguna demora indebida y a m\u00e1s tardar 14 d\u00edas naturales, a partir de la fecha en la que haya recibido tu decisi\u00f3n de desistir del contrato. Proceder\u00e9 a efectuar dicho reembolso utilizando el mismo medio de pago empleado por ti para la transacci\u00f3n inicial.<\/span><\/p><p><span style=\"font-weight: 400;\">&#8211; <\/span><b>Podr\u00e9 retener el reembolso hasta haber recibido de vuelta los productos enviados<\/b><span style=\"font-weight: 400;\"> (tanto la obra como su embalaje), o hasta que hayas presentado una prueba de la devoluci\u00f3n de los mismos, seg\u00fan qu\u00e9 condici\u00f3n se cumpla primero. Valdr\u00e1 como prueba el justificante de env\u00edo en la empresa de transportes, junto con una declaraci\u00f3n jurada sobre el contenido.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">&#8211; <\/span><b>Deber\u00e1s entregarme directamente los bienes o si no asumir el coste directo de la devoluci\u00f3n a trav\u00e9s de una empresa de transportes<\/b><span style=\"font-weight: 400;\">. La direcci\u00f3n en la que se deber\u00e1 realizar la devoluci\u00f3n es la siguiente:\u00a0<\/span><\/p><p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">Destinatario: Pedro Amutio Fern\u00e1ndez.\u00a0<\/span><\/p><p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">Direcci\u00f3n: R\u00faa \u00c1lvaro Cunqueiro, n\u00ba 13, 5\u00ba B. CP 36211, Vigo, provincia de Pontevedra (Espa\u00f1a).<\/span><\/p><p><span style=\"font-weight: 400;\">&#8211; Deber\u00e1s realizar el env\u00edo sin ninguna demora indebida y, en cualquier caso, a m\u00e1s tardar en el plazo de 14 d\u00edas naturales a partir de la fecha en que hayas comunicado tu decisi\u00f3n de desistimiento del contrato.<\/span><\/p><p><span style=\"font-weight: 400;\">&#8211; Deber\u00e1s enviar la obra con los mismos elementos de protecci\u00f3n que recibas. Por ello recomiendo no tirar el embalaje hasta verificar que no vas a proceder a la devoluci\u00f3n de la obra recibida.<\/span><\/p><p><span style=\"font-weight: 400;\">Si has tirado el embalaje de protecci\u00f3n deber\u00e1s usar el mismo tipo de material para evitar da\u00f1os a la obra durante el transporte. Ser\u00e1s responsable de la disminuci\u00f3n de valor de la obra, a consecuencia de los da\u00f1os sufridos en el trasporte por no haber devuelto la obra correctamente embalada.<\/span><\/p><p><span style=\"font-weight: 400;\">Aunque optes por devolverme personalmente la obra <\/span><b>deber\u00e1s entregarme tambi\u00e9n el embalaje con el que se te envi\u00f3<\/b><span style=\"font-weight: 400;\">, o comprar uno similar (en caso de que lo hayas tirado), o bien entregarme el importe de su coste, el cual es aproximadamente de 10 \u20ac.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">As\u00ed podr\u00e9 reutilizar dicho embalaje y no perder ese material adem\u00e1s de los gastos de haber realizado el env\u00edo. Considero que es un trato equilibrado, teniendo en cuenta que tienes derecho a devolver la obra sin necesidad de justificarlo.<\/span><\/p><p><a href=\"https:\/\/perihelio.es\/wp-content\/uploads\/2022\/04\/ANEXO-1-MODELO-DE-FORMULARIO-DE-DESISTIMIENTO.docx.pdf\" target=\"_blank\" rel=\"noopener\">ver ANEXO 2 &#8211; modelo de formulario de desestimiento<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CONDICIONES CONTRACTUALES DE COMPRA El principal fin de mi Sitio web es la exposici\u00f3n y difusi\u00f3n de mis obras art\u00edsticas. Las reproducciones (impresiones digitales seriadas, serigraf\u00edas u otros tipos) de algunas de mis obras podr\u00e1n ser adquiridas conforme a las condiciones de este documento.\u00a0 Las obras originales se pueden adquirir previo encargo espec\u00edfico a trav\u00e9s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-18158","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Peri Helio - Artista multidisciplinar - Pol\u00edtica de privacidad<\/title>\n<meta name=\"description\" content=\"Peri Helio, licenciado en matem\u00e1ticas (especialidad de astronom\u00eda). De formaci\u00f3n autodidacta, su trayectoria nace ligada al arte urbano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perihelio.es\/en\/condiciones-de-contratacion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peri Helio - Artista multidisciplinar - Pol\u00edtica de privacidad\" \/>\n<meta property=\"og:description\" content=\"Peri Helio, licenciado en matem\u00e1ticas (especialidad de astronom\u00eda). De formaci\u00f3n autodidacta, su trayectoria nace ligada al arte urbano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perihelio.es\/en\/condiciones-de-contratacion\/\" \/>\n<meta property=\"og:site_name\" content=\"PERI\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-29T16:38:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perihelio.es\\\/en\\\/condiciones-de-contratacion\\\/\",\"url\":\"https:\\\/\\\/perihelio.es\\\/en\\\/condiciones-de-contratacion\\\/\",\"name\":\"Peri Helio - Artista multidisciplinar - Pol\u00edtica de privacidad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perihelio.es\\\/#website\"},\"datePublished\":\"2022-04-01T08:42:00+00:00\",\"dateModified\":\"2023-09-29T16:38:12+00:00\",\"description\":\"Peri Helio, licenciado en matem\u00e1ticas (especialidad de astronom\u00eda). De formaci\u00f3n autodidacta, su trayectoria nace ligada al arte urbano.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perihelio.es\\\/en\\\/condiciones-de-contratacion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perihelio.es\\\/en\\\/condiciones-de-contratacion\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perihelio.es\\\/en\\\/condiciones-de-contratacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/perihelio.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Condiciones de contrataci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perihelio.es\\\/#website\",\"url\":\"https:\\\/\\\/perihelio.es\\\/\",\"name\":\"PERI\",\"description\":\"Ilustraci\u00f3n y Murales en Vigo\",\"publisher\":{\"@id\":\"https:\\\/\\\/perihelio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perihelio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perihelio.es\\\/#organization\",\"name\":\"PERI\",\"url\":\"https:\\\/\\\/perihelio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/perihelio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perihelio.es\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-firma-Peri.jpg\",\"contentUrl\":\"https:\\\/\\\/perihelio.es\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-firma-Peri.jpg\",\"width\":150,\"height\":487,\"caption\":\"PERI\"},\"image\":{\"@id\":\"https:\\\/\\\/perihelio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peri Helio - Artista multidisciplinar - Pol\u00edtica de privacidad","description":"Peri Helio, licenciado en matem\u00e1ticas (especialidad de astronom\u00eda). De formaci\u00f3n autodidacta, su trayectoria nace ligada al arte urbano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perihelio.es\/en\/condiciones-de-contratacion\/","og_locale":"en_US","og_type":"article","og_title":"Peri Helio - Artista multidisciplinar - Pol\u00edtica de privacidad","og_description":"Peri Helio, licenciado en matem\u00e1ticas (especialidad de astronom\u00eda). De formaci\u00f3n autodidacta, su trayectoria nace ligada al arte urbano.","og_url":"https:\/\/perihelio.es\/en\/condiciones-de-contratacion\/","og_site_name":"PERI","article_modified_time":"2023-09-29T16:38:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/perihelio.es\/en\/condiciones-de-contratacion\/","url":"https:\/\/perihelio.es\/en\/condiciones-de-contratacion\/","name":"Peri Helio - Artista multidisciplinar - Pol\u00edtica de privacidad","isPartOf":{"@id":"https:\/\/perihelio.es\/#website"},"datePublished":"2022-04-01T08:42:00+00:00","dateModified":"2023-09-29T16:38:12+00:00","description":"Peri Helio, licenciado en matem\u00e1ticas (especialidad de astronom\u00eda). De formaci\u00f3n autodidacta, su trayectoria nace ligada al arte urbano.","breadcrumb":{"@id":"https:\/\/perihelio.es\/en\/condiciones-de-contratacion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perihelio.es\/en\/condiciones-de-contratacion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/perihelio.es\/en\/condiciones-de-contratacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/perihelio.es\/en\/"},{"@type":"ListItem","position":2,"name":"Condiciones de contrataci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/perihelio.es\/#website","url":"https:\/\/perihelio.es\/","name":"PERI","description":"Ilustraci\u00f3n y Murales en Vigo","publisher":{"@id":"https:\/\/perihelio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perihelio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/perihelio.es\/#organization","name":"PERI","url":"https:\/\/perihelio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/perihelio.es\/#\/schema\/logo\/image\/","url":"https:\/\/perihelio.es\/wp-content\/uploads\/2021\/07\/Logo-firma-Peri.jpg","contentUrl":"https:\/\/perihelio.es\/wp-content\/uploads\/2021\/07\/Logo-firma-Peri.jpg","width":150,"height":487,"caption":"PERI"},"image":{"@id":"https:\/\/perihelio.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/perihelio.es\/en\/wp-json\/wp\/v2\/pages\/18158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perihelio.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/perihelio.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/perihelio.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/perihelio.es\/en\/wp-json\/wp\/v2\/comments?post=18158"}],"version-history":[{"count":16,"href":"https:\/\/perihelio.es\/en\/wp-json\/wp\/v2\/pages\/18158\/revisions"}],"predecessor-version":[{"id":20701,"href":"https:\/\/perihelio.es\/en\/wp-json\/wp\/v2\/pages\/18158\/revisions\/20701"}],"wp:attachment":[{"href":"https:\/\/perihelio.es\/en\/wp-json\/wp\/v2\/media?parent=18158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}